{"id":1755,"date":"2020-12-02T09:33:10","date_gmt":"2020-12-02T08:33:10","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\/"},"modified":"2021-01-18T13:33:08","modified_gmt":"2021-01-18T12:33:08","slug":"forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\/","title":{"rendered":"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"Forum QualEnergia 2020\" loading=\"lazy\" style=\"display: block; margin-bottom: 5px; clear:both;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><em>\u00c8 uno dei temi al centro della XIII edizione del Forum organizzato da Legambiente, La Nuova Ecologia e Kyoto Club<\/em><\/p>\n<p><span id=\"more-239124\"><\/span><\/p>\n<p>In Italia le comunit\u00e0 energetiche possono essere la carta vincente nel cruciale processo di decarbonizzazione. Un loro pieno sviluppo su tutto il loro territorio nazionale pu\u00f2 giovare all\u2019ambiente, all\u2019economia, all\u2019occupazione e pu\u00f2 favorire soprattutto il processo di decarbonizzazione nei settori termico e dei trasporti. \u00c8 questo il messaggio e la sfida che Legambiente lancia oggi al Governo in occasione della due giorni del <a href=\"https:\/\/staging.forumqualenergia.it\/2023\/programma-2020\/\"><strong>Forum QUALENERGIA<\/strong><\/a>, il talk online organizzato il 2 e 3 dicembre insieme a La Nuova Ecologia e Kyoto Club, per fare il punto insieme ad esperti del settore e rappresentanti istituzionali su quello che deve essere il sesto pilastro del Recovery Plan italiano &#8211; l\u2019efficienza energetica \u2013 in un\u2019ottica di scambio e condivisione di energia prodotta da fonti rinnovabili da mettere in campo su tutto il territorio. Il Forum viene <a href=\"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-comunita-energetiche\/\"><strong>trasmesso oggi e domani in diretta streaming<\/strong><\/a> sulle pagine Facebook di Legambiente, QualEnergia e La Nuova Ecologia e sui rispettivi siti.<\/p>\n<h3><strong>Verso la decarbonizzazione del Paese<\/strong><\/h3>\n<p>A parlar chiaro sono anche dati dello studio <em>Il contributo delle comunit\u00e0 energetiche alla decarbonizzazione in Italia<\/em> realizzato da <strong>Elemens <\/strong>per <strong>Legambiente <\/strong>e che verr\u00e0 presentato oggi, in cui ipotizzando un pieno recepimento della Direttiva RED II e IEM si descrive lo scenario di sviluppo dei prossimi anni, sintetizzando opportunit\u00e0 e benefici ottenibili grazie allo sviluppo sulla Penisola delle comunit\u00e0 energetiche,\u00a0con opportunit\u00e0 che si possono creare dai condomini ai centri commerciali, dai distretti industriali alle aree agricole interne.<\/p>\n<p><iframe title=\"Scelte per il rilancio delle rinnovabili Forum QualEnergia 2020\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/qZ3RydhaAgY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Gi\u00e0 entro il 2030 si stima che il contributo delle Energy Community possa arrivare a <strong>17,2 GW di nuova capacit\u00e0 rinnovabile <\/strong>permettendo di incrementare, sempre al 2030, la produzione elettrica di rinnovabili di circa 22,8TWh, coprendo il 30% circa dell\u2019incremento di energia verde prevista dal PNIEC per centrare i nuovi target di decarbonizzazione individuati a livello europeo.<strong> Notevoli anche i benefici a cui si andrebbe incontro: <\/strong>il completo recepimento della Direttiva RED II permetterebbe una forte diffusione delle Energy Community su tutto il territorio nazionale con <strong>investimenti in nuova capacit\u00e0 rinnovabile<\/strong> stimati <strong>in 13,4 miliardi di euro nel periodo 2021 \u2013 2030<\/strong> in caso di attivazione di tutto il potenziale. Gli investimenti attivati genererebbero ricadute economiche sulle imprese italiane attive lungo la filiera delle rinnovabili pari a circa <strong>2,2 miliardi di euro in termini di valore aggiunto contabile<\/strong>. A ci\u00f2 andrebbero poi ad aggiungersi importanti <strong>vantaggi fiscali<\/strong>, si stima un incremento del gettito fiscale di circa <strong>1,1 miliardi di euro<\/strong>, &#8211; ma anche <strong>vantaggi ambientali<\/strong> visto che lo sviluppo delle Energy Community in Italia comporterebbe una riduzione delle CO<sub>2<\/sub> al 2030 stimata in <strong>47,1 milioni di tonnellate. In termini occupazionali, <\/strong>si stima nel periodo 2021-2030 un impatto in termini di unit\u00e0 lavorative dirette &#8211; relative solo al lato \u00abimpianti\u00bb &#8211; pari a 19.000 addetti, senza considerare l\u2019indotto che si verrebbe a creare attraverso gli interventi di efficienza energetica e gestione degli impianti, di integrazione della mobilit\u00e0 sostenibile, che si pu\u00f2 stimare di almeno altrettanti. Dati importanti che indicano quale sia la strada da seguire. Per questo per l\u2019associazione ambientalista \u00e8 fondamentale che il Paese acceleri al pi\u00f9 presto nella direzione della comunit\u00e0 energetiche e che il <strong>Governo entro giugno 2021 recepisca le due direttive europee che aprono a questo scenario di condivisione e autoproduzione dell&#8217;energia prodotta da rinnovabili.<\/strong> Ora il Disegno di Legge delega \u00e8 alla Camera per l&#8217;approvazione, poi spetter\u00e0 all\u2019Esecutivo presentare un Decreto legislativo. In questa fase Legambiente chiede che si apra un confronto sugli obiettivi e sulle scelte trasparente, perch\u00e9 siamo di fronte a uno scenario di enorme rilevanza per l\u2019Italia.<\/p>\n<p>\u201cIl Recovery Plan italiano &#8211; dichiara <strong>Stefano Ciafani, presidente nazionale di Legambiente<\/strong> \u2013 deve avere tra i suoi pilastri il miglioramento dell\u2019efficienza energetica, lo sviluppo delle rinnovabili, del biometano e della mobilit\u00e0 elettrica dandosi come obiettivo prioritario quello di accelerare la diffusione su tutto il territorio nazionale delle comunit\u00e0 energetiche. Il Governo non perda questa importante occasione, \u00e8 ora di fare scelte chiari e radicali non pi\u00f9 rimandabili smettendola di foraggiare i petrolieri, decarbonizzando l\u2019economia attraverso l\u2019eliminazione graduale degli oltre 19 miliardi di euro l\u2019anno di sussidi diretti e indiretti alle fonti fossili e accelerando la transizione verde della Penisola, aiutando allo stesso tempo e imprese a scegliere questo scenario di condivisione e autoproduzione dell&#8217;energia prodotta da fonti pulite. Senza dimenticare che tra gli altri interventi da mettere in campo per accelerare la transizione energetica del Paese, occorre promuovere le semplificazioni autorizzative per la realizzazione degli impianti a fonti rinnovabili, senza le quali la rivoluzione energetica non si concretizzer\u00e0\u201d.<\/p>\n<p>\u201cLo studio sulle comunit\u00e0 energetiche \u2013 spiega <strong>Edoardo Zanchini, vicepresidente di Legambiente<\/strong> &#8211;\u00a0 dimostra le grandi potenzialit\u00e0 nel nostro Paese di uno scenario di condivisione e autoproduzione dell&#8217;energia che ha grandi vantaggi perch\u00e9 permette di sviluppare le rinnovabili laddove c\u2019\u00e8 la domanda, nei quartieri, nei distretti produttivi, nelle aree interne e agricole. Per l&#8217;Italia vuol dire rilanciare il settore edilizio, che pu\u00f2 puntare su progetti integrati di efficienza energetica e di rinnovabili con le comunit\u00e0 energetiche, ma anche con la connessione alla mobilit\u00e0 elettrica. Sono progetti che vedranno protagonisti cittadini, imprese, enti locali, associazioni, con il vantaggio di puntare a sistemi energetici totalmente elettrici e da rinnovabili, riuscendo cos\u00ec a risparmiare e arrivare a cancellare\u00a0i consumi di gas per il riscaldamento delle case e di benzina\/diesel per la mobilit\u00e0. Alla politica &#8211; continua <strong>Zanchini <\/strong>&#8211; chiediamo di accelerare nella direzione della comunit\u00e0 energetiche, noi daremo il nostro contributo come Legambiente, come abbiamo fatto in questi mesi con la proposta di recepimento anticipato per impianti fino a 200kW \u00a0presentata insieme ad Italia Solare ed entrata in vigore con il Milleproroghe e che ora consente di far partire le prime comunit\u00e0 energetiche. Per cui il 2021 sar\u00e0 un anno fondamentale, per questi primi interventi che vedranno la luce e per la definizione delle norme che apriranno a questi interventi in ogni dimensione e territorio\u201d.<\/p>\n<p><iframe title=\"Mercati ed energia tra decarbonizzazione e digitale\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/J2ZYh1zf_BI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3><strong>Il ruolo centrale delle comunit\u00e0 energetiche<\/strong><\/h3>\n<p>Tornando ai dati dello studio Elemens, altra questione interessante che emerge riguarda il fatto che <strong>le Energy Community possono favorire il processo di decarbonizzazione nei settori termico e trasporti.<\/strong> Il minor costo dell\u2019energia autoconsumata rispetto a quella prelevata dalla rete, infatti, renderebbe ancor pi\u00f9 conveniente l\u2019installazione di sistemi di riscaldamento quali le pompe di calore, che verrebbero cos\u00ec alimentate dall\u2019energia prodotta dagli impianti a fonti rinnovabili presenti all\u2019interno della comunit\u00e0 energetica, con ulteriori benefici ambientali in termini di riduzione delle emissioni. Per quanto riguarda la decarbonizzazione dei trasporti, l\u2019energia elettrica prodotta dagli impianti rinnovabili installati nella comunit\u00e0 energetica potrebbe anche essere utilizzata per alimentare delle stazioni di ricarica dei veicoli elettrici (pubbliche ma anche dei singoli privati) contribuendo, anche in questo caso, a traslare i consumi energetici dei trasporti da combustibili fossili a energia elettrica prodotta da fonti rinnovabili, accelerando il processo di decarbonizzazione del Paese.<\/p>\n<p>\u201cL\u2019Europa ce lo chiede, l\u2019innovazione tecnologica ci offre una grande opportunit\u00e0: rinnovabili ed efficienza energetica possono essere le chiavi di volta per la ripresa economica e sociale che dobbiamo assolutamente saper cogliere dopo la crisi pandemica. Eppure la politica nostrana \u00e8 ancora troppo timida (potendo vantare al suo attivo praticamente solo il super bonus) e sembra di mancare di quella visione del futuro che sarebbe necessaria. Il tempo scorre e se vogliamo affrontare crisi climatica e non perdere la gara con i nostri competitors internazionali dobbiamo invece accelerare subito\u201d, dichiara<strong> Francesco Ferrante vicepresidente del Kyoto Club.<\/strong><\/p>\n<p><iframe title=\"Economia circolare e fotovoltaico per uno sviluppo sostenibile\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/IcZNOEzwsuk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Infine Legambiente nel corso della prima giornata del Forum, in diretta streaming sulle pagine Fb di Legambiente, QualEnergia, La Nuova Ecologia, sui rispettivi siti e il canale You Tube Legambiente, ha anche rilanciato alcune sue proposte chiedendo:<strong> un salto di scala industriale, territoriale e comunitario per le fonti rinnovabili <\/strong>prevedendo impianti eolici offshore e solari a terra in aree dismesse, la diffusione delle Comunit\u00e0 energetiche e l\u2019autoproduzione da fonti rinnovabili; <strong>dimezzare i consumi energetici del patrimonio edilizio pubblico e privato<\/strong> prevedendo la proroga del superbonus al 2025 con revisione dei criteri in modo da spingere l\u2019efficienza energetica e le fonti rinnovabili in sostituzione degli impianti a gas. Prevedere l\u2019introduzione di un fondo per l\u2019accesso al credito da parte delle famiglie per gli interventi di efficienza energetica;<strong> innovazione e giusta transizione nei territori della rivoluzione industriale<\/strong> finanziando con le risorse del Just transition fund gli interventi di rigenerazione ambientale e rilancio economico e industriale\u00a0delle aree della transizione energetica e della dismissione produttiva.\u00a0\u00a0Fare di Taranto e Brindisi il distretto dell\u2019innovazione industriale green. 4)<strong> Ridurre il gap nell\u2019accesso alla mobilit\u00e0 sostenibile tra i territori e nelle periferie <\/strong>completando l\u2019elettrificazione delle linee ferroviarie e l\u2019installazione del sistema di controllo e sicurezza\u00a0(SCMT) al Sud, nelle isole, nelle linee nazionali e regionali ancora sprovviste. Acquistando treni con standard ad alta velocit\u00e0 al sud e lanciare una gara per aumentare l\u2019offerta di servizio; realizzando un progetto di rilancio delle infrastrutture di mobilit\u00e0 sostenibile nelle aree urbane italiane e adeguamento dell\u2019offerta di servizio.<\/p>\n<p>Il Forum proseguir\u00e0 domani gioved\u00ec 3 dicembre alle ore 10.00, sempre in diretta streaming, con la presentazione del <strong>sondaggio Ipsos <em>Gli Italiani e l\u2019energia<\/em><\/strong>, a cura di Andrea Alemanno\u00a0Responsabile Ricerche Sostenibilit\u00e0 IPSOS e Luca Biamonte\u00a0Direttore Relazioni Esterne e Comunicazione Editoriale Nuova Ecologia e nel pomeriggio, ore 14.30, la presentazione del <strong><em>Rapporto CIVICO 5.0 sull\u2019efficienza energetica in edilizia<\/em><\/strong> a cura di Katiuscia Eroe Responsabile Energia Legambiente e di Sibilla Amato Ufficio Energia Legambiente.<\/p>\n<p><iframe title=\"Green mobility elettrica connessa condivisa\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/Oa3mdu2Eq3U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3><strong>I prossimi appuntamenti<\/strong><\/h3>\n<p>Il Forum QUALENERGIA, giunto alla XIII edizione, \u00e8 il sesto di sette incontri tematici organizzati da Legambiente\u00a0con istituzioni, imprese e associazioni per individuare le migliori proposte per il Piano nazionale di ripresa e resilienza che il Governo italiano dovr\u00e0 presentare in Europa entro aprile 2021. Il prossimo appuntamento in programma la presentazione del Rapporto Ecomafia l\u201911 dicembre.<\/p>\n<h3><strong><a href=\"https:\/\/a2f3e0.emailsp.com\/frontend\/forms\/Subscription.aspx?idList=3&amp;idForm=6&amp;guid=3a0cb849-9df7-455a-8512-dc7199ae3fd8\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong><\/h3>\n<h3><strong><a href=\"https:\/\/www.lanuovaecologia.it\/acquista\/\">SOSTIENI IL MENSILE<\/a><\/strong><\/h3>\n<\/p>\n<p align=\"right\"><strong>Rocco Bellantone<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 uno dei temi al centro della XIII edizione del Forum organizzato da Legambiente, La Nuova Ecologia e Kyoto Club In Italia le comunit\u00e0 energetiche possono essere la carta vincente nel cruciale processo di decarbonizzazione. Un loro pieno sviluppo su tutto il loro territorio nazionale pu\u00f2 giovare all\u2019ambiente, all\u2019economia, all\u2019occupazione e pu\u00f2 favorire soprattutto il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"\u00c8 uno dei temi al centro della XIII edizione del Forum organizzato da Legambiente, La Nuova Ecologia e Kyoto Club In Italia le comunit\u00e0 energetiche possono essere la carta vincente nel cruciale processo di decarbonizzazione. Un loro pieno sviluppo su tutto il loro territorio nazionale pu\u00f2 giovare all\u2019ambiente, all\u2019economia, all\u2019occupazione e pu\u00f2 favorire soprattutto il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T08:33:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-18T12:33:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\\\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione\",\"datePublished\":\"2020-12-02T08:33:10+00:00\",\"dateModified\":\"2021-01-18T12:33:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\\\/\"},\"wordCount\":1627,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/PHOTO-2020-12-02-14-53-11.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/\",\"name\":\"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/PHOTO-2020-12-02-14-53-11.jpg\",\"datePublished\":\"2020-12-02T08:33:10+00:00\",\"dateModified\":\"2021-01-18T12:33:08+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/forum-qualenergia-2020-programma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/PHOTO-2020-12-02-14-53-11.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/PHOTO-2020-12-02-14-53-11.jpg\",\"width\":630,\"height\":420},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\\\/\\\/forumqualenergia.it\"],\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/ecfrm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/","og_locale":"it_IT","og_type":"article","og_title":"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione - ForumQualEnergia 2023","og_description":"\u00c8 uno dei temi al centro della XIII edizione del Forum organizzato da Legambiente, La Nuova Ecologia e Kyoto Club In Italia le comunit\u00e0 energetiche possono essere la carta vincente nel cruciale processo di decarbonizzazione. Un loro pieno sviluppo su tutto il loro territorio nazionale pu\u00f2 giovare all\u2019ambiente, all\u2019economia, all\u2019occupazione e pu\u00f2 favorire soprattutto il [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2020-12-02T08:33:10+00:00","article_modified_time":"2021-01-18T12:33:08+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\/"},"author":{"name":"ecfrm","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione","datePublished":"2020-12-02T08:33:10+00:00","dateModified":"2021-01-18T12:33:08+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\/"},"wordCount":1627,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/forum-qualenergia-2020-comunita-energetiche-motore-per-la-decarbonizzazione\/","url":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/","name":"Forum QualEnergia 2020, comunit\u00e0 energetiche motore per la decarbonizzazione - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg","datePublished":"2020-12-02T08:33:10+00:00","dateModified":"2021-01-18T12:33:08+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/forum-qualenergia-2020-programma\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/PHOTO-2020-12-02-14-53-11.jpg","width":630,"height":420},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=1755"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/1773"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=1755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=1755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}