{"id":1838,"date":"2020-12-07T10:57:11","date_gmt":"2020-12-07T09:57:11","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/"},"modified":"2021-01-18T13:33:06","modified_gmt":"2021-01-18T12:33:06","slug":"il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/","title":{"rendered":"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"202\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" loading=\"lazy\" style=\"display: block; margin-bottom: 5px; clear:both;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg 448w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h6>Ancora rinvii nonostante gli impegni del governo: 35,7 miliardi sottratti all\u2019innovazione ambientale. Legambiente presenta il Rapporto Stop sussidi alle fonti fossili e ambientalmente dannosi<\/h6>\n<p>&nbsp;<\/p>\n<p><strong>Anche il 2020 si chiude senza tagli ai sussidi alle fonti fossili<\/strong>; nella legge di bilancio presentata dal governo il tema non \u00e8 previsto, nonostante sia stata istituita quest\u2019anno una \u201cCommissione interministeriale per lo studio e l\u2019elaborazione di proposte per la transizione ecologica e per la riduzione dei\u00a0<strong>sussidi ambientalmente dannosi<\/strong>\u201d. Sussidi<strong>\u00a0stimabili, complessivamente, in<\/strong>\u00a0<strong>35,7 miliardi di euro<\/strong>, di cui oltre\u00a021,8\u00a0miliardi sotto forma diretta e circa\u00a013,8\u00a0miliardi in forma indiretta.<\/p>\n<p>Parliamo di tutte le misure incentivanti, che intervengono su beni o lavorazioni, per ridurre il costo di utilizzo di fonti fossili o di sfruttamento delle risorse\u00a0naturali.\u00a0<strong>Il\u00a0quadro completo<\/strong>\u00a0delle voci e delle cifre \u00e8 ricostruito\u00a0nel nuovo rapporto presentato oggi da Legambiente, per far capire la dimensione e l\u2019importanza delle decisioni da prendere. Larga parte va alle\u00a0<strong>imprese, oltre\u00a023\u00a0miliardi<\/strong>, e\u00a0<strong>12,5\u00a0miliardi alle famiglie<\/strong>. La quota pi\u00f9 rilevante dei sussidi diretti riguarda il settore\u00a0<strong>dei trasporti, per 11 miliardi; seguono l\u2019energia con 10,6 e l\u2019agricoltura con 0,1.<\/strong><\/p>\n<p>Il rapporto (che unisce fonti diverse tra cui il Catalogo SAF e SAD, il bilancio dello Stato, dati Terna, Arera, GSE e MISE) analizza il settore energetico ma anche trasporti, agricoltura, canoni ed edilizia. Riporta\u00a0<strong>voci molto differenti &#8211; da incentivi diretti e indiretti a sconti sulle tasse, a finanziamenti dati da imprese e societ\u00e0 dello Stato<\/strong>\u00a0&#8211; ognuna nata con\u00a0<strong>l\u2019obiettivo, condivisibile<\/strong>, di ridurre i costi a vantaggio di imprese e famiglie, ma\u00a0<strong>\u00e8 il mezzo che oggi non funziona pi\u00f9<\/strong>: bisogna guardare alle ragioni per cui si confermano sussidi che producono un impatto negativo su ambiente e clima quando esistono alternative competitive.<\/p>\n<p>Alcuni di questi sussidi sono stati addirittura introdotti nel 2020, come il\u00a0<strong>capacity market<\/strong>, che prevede 20 anni di generosissimi incentivi per nuove centrali a gas, giustificati da ragioni di sicurezza del sistema; quando per la flessibilit\u00e0 e la sicurezza del sistema esistono alternative pi\u00f9 economiche, efficienti e con ridotte o zero emissioni di gas serra. Il paradosso dei sussidi alle fonti fossili, come sottolineato da Fatih Birol, capo economista dell\u2019International Energy Agency, \u00e8 che\u00a0<strong>sono oggi il principale ostacolo allo sviluppo delle rinnovabili e di interventi di efficienza energetica<\/strong>\u00a0che sarebbero competitivi in ogni parte del mondo, ma che invece vedono privilegiare con carbone, gas e petrolio, resi artificialmente economici dagli aiuti pubblici.<\/p>\n<p><strong>\u201cNon esiste scusa legata al Covid\u00a0<\/strong>che<strong>\u00a0<\/strong>tenga\u00a0<strong>&#8211;<\/strong>\u00a0<strong>dichiara Edoardo Zanchini, vicepresidente di Legambiente\u00a0&#8211;\u00a0<\/strong>perch\u00e9 l\u2019emergenza climatica sta diventando sempre pi\u00f9 grave e perch\u00e9<strong>\u00a0ogni euro non pi\u00f9 regalato a chi inquina pu\u00f2 liberare investimenti in innovazione ambientale ma anche per far uscire il Paese dalla crisi economica e sociale<\/strong>. Nelle proposte che presentiamo oggi dimostriamo come sia possibile intervenire subito sui sussidi alle fonti fossili e all\u2019estrazione di materiali naturali, mentre il\u00a0<strong>Recovery Plan italiano<\/strong>\u00a0dovr\u00e0 fissare le riforme e la tempistica per cancellare tutti i sussidi entro il 2030\u201d.<\/p>\n<p>Nel 2017 il ministero dell\u2019Ambiente ha presentato il primo \u201cCatalogo dei Sussidi ambientalmente dannosi e favorevoli\u201d, aggiornato nel 2019; il tema \u00e8 finalmente nel dibattito politico, ma i risultati finora sono deludenti, con un intervento limitato di adeguamento dei canoni per le estrazioni di fonti fossili e di eliminazione del rimborso accise gasolio per i camion con standard di emissioni euro 3 ed euro 4.<\/p>\n<p><strong>I sussidi ambientalmente dannosi<\/strong>\u00a0<strong>sono finanziamenti diretti a centrali che utilizzano derivati del petrolio, gas e carbone, che inquinano e producono emissioni di gas serra,\u00a0<\/strong>come le<strong>\u00a0<\/strong>centrali di Brindisi Sud e Fiumesanto o di San Filippo Mela, che rimangono accese solo perch\u00e9 ricevono generosi sussidi, altrimenti in larga parte sarebbero fuori mercato. Oppure centrali diesel nelle isole minori italiane che potrebbero essere sostituite da ben pi\u00f9 economici ed efficienti impianti solari ed eolici.\u00a0<strong>Sono sconti su tasse (accisa, iva e credito d\u2019imposta) per una serie enorme di utilizzi di benzina, gasolio, gas, ecc. nei trasporti, nel riscaldamento, nelle industrie.<\/strong>\u00a0Per chiarezza, di questi sconti beneficiano famiglie e imprese, per cui un semplice taglio avrebbe effetti negativi da un punto di vista economico e sociale, per le famiglie pi\u00f9 povere e le imprese pi\u00f9 in difficolt\u00e0. Ma invece si pu\u00f2 e si deve far diventare questi sconti sui consumi, incentivi verso investimenti in efficienza e nell\u2019autoproduzione da rinnovabili, con risultati strutturali in termini di risparmio oltre che vantaggi ambientali.\u00a0Sono canoni bassi per l\u2019estrazione di materie prime, per l\u2019imbottigliamento di acqua, sono tasse limitate per chi butta i rifiuti riciclabili in discarica.\u00a0<strong>Sono anche finanziamenti ad autostrade, a componentistica, impianti per la fertilizzazione e fondi per la ricerca su carbone, gas e petrolio. In Italia e all\u2019estero.<\/strong><\/p>\n<p>\u201cCon questo lavoro vogliamo dare il nostro contributo nel dimostrare quanto sia urgente cambiare il sistema di sussidi di cui beneficiano tante attivit\u00e0 inquinanti nel nostro Paese &#8211;\u00a0<strong>dichiara Katiuscia Eroe, responsabile energia di Legambiente<\/strong>\u00a0&#8211; Non tutto \u00e8 cancellabile dall\u2019oggi al domani ma \u00e8 certo che serve intervenire, partendo dai finanziamenti pi\u00f9 assurdi, inquinanti, a premio di rendite contro l\u2019ambiente. I sussidi dannosi sono un macigno sulla possibilit\u00e0 di spingere una innovazione diffusa, nell\u2019interesse del Paese; sono risorse sottratte a investimenti di cui c\u2019\u00e8 enorme bisogno per uscire dalla crisi: potrebbero andare a ospedali, scuole, ricerca, investimenti nella green economy e nella riduzione delle diseguaglianze.\u00a0Esistono oggi alternative da fonti rinnovabili meno costose in tanti campi, mentre in altri si dovrebbe promuovere l\u2019efficienza nell\u2019uso dei combustibili invece di fare sconti\u201d.<\/p>\n<p><strong>\u00c8 stato presentato oggi anche il <a href=\"https:\/\/www.lanuovaecologia.it\/nessun-paese-linea-obiettivi-accordo-parigi\/\">rapporto annuale di Germanwatch<\/a><\/strong>, CAN e NewClimate Institute sulla\u00a0<strong>performance climatica<\/strong>\u00a0dei principali paesi del pianeta, realizzato in collaborazione con Legambiente per l\u2019Italia, che rileva\u00a0<strong>ancora un passo indietro per l\u2019Italia, che scende al 27\u00b0posto<\/strong>\u00a0rispetto al 26\u00b0 dello scorso anno. Risultato dovuto al rallentamento dello sviluppo delle rinnovabili (31\u00b0) e a una politica climatica nazionale inadeguata agli obiettivi di Parigi, peraltro non raggiunti da nessun paese: infatti, il Piano Nazionale Integrato Energia e Clima (PNIEC) consente un taglio delle emissioni entro il 2030 del solo 37%, con una riduzione media annua di appena l\u20191,7% a partire dal 2020, obiettivo fortemente inadeguato.\u00a0<strong>Rendendo ancora pi\u00f9 urgenti i tagli ai sussidi ambientalmente dannosi<\/strong>, di cui seguono i principali numeri per settore del\u00a0<a href=\"http:\/\/www.comunirinnovabili.it\/stop-sussidi-alle-fonti-fossili-e-ambientalmente-dannosi\/\">dossier Stop Sussidi<\/a>\u00a0e\u00a0<strong>le relative proposte di Legambiente<\/strong>.<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong><u>Settore energia<\/u><\/strong><\/p>\n<p>Sono\u00a0<strong>15 i miliardi di euro<\/strong>\u00a0destinati, nel 2019, a sussidiare il settore energetico fossile del nostro Paese; che diventano 15,8 miliardi per il 2020. Ventisei\u00a0<strong>sussidi diversi<\/strong>, di cui almeno\u00a0<strong>14 potrebbero essere eliminati subito, per un valore pari a 8,6 miliardi di euro<\/strong>.\u00a0<strong>Sono invece\u00a0<\/strong><strong>6,3<\/strong><strong>\u00a0i miliardi euro di sussidi che andrebbero rimodulati<\/strong>, in quanto strettamente connessi con settori strategici produttivi o di consumo, come quelli delle isole minori o delle aree geograficamente svantaggiate o ancora la riduzione dell\u2019iva per imprese e utenti domestici. In particolare, le\u00a0<strong>trivellazioni ricevono sussidi indiretti per 576, 54 milioni di euro, dovuti all\u2019inadeguatezza di<\/strong>\u00a0<strong>royalties e canoni<\/strong>. I\u00a0<strong>contributi a centrali fossili e impianti\u00a0<\/strong>sono costati, nel 2019, ai contribuenti italiani,\u00a0<strong>1.316,4 milioni di euro<\/strong>; di cui\u00a0<strong>412,4 milioni di euro<\/strong>\u00a0sono andati ai cosiddetti \u201cimpianti essenziali\u201d su terra ferma e nelle isole minori;\u00a0<strong>500 milioni\u00a0<\/strong>di euro di indennizzo sono andati invece agli\u00a0<strong>interconnector<\/strong>, linee elettriche finanziate da soggetti privati. Al\u00a0<strong>Capacity Market<\/strong>\u00a0nel 2020 vanno<strong>\u00a0180 milioni<\/strong>\u00a0di euro di sussidi diretti, mentre il\u00a0<strong>CIP6<\/strong>\u00a0continua a ricevere sussidi per\u00a0<strong>682 milioni<\/strong>\u00a0all\u2019anno. I\u00a0<strong>prestiti e le garanzie pubbliche<\/strong>\u00a0(CDP e SACE) per operazioni a sostegno di investimenti nell\u2019Oil&amp;Gas ammontano a\u00a0<strong>3.756 milioni<\/strong>\u00a0di euro. Senza dimenticare gli assurdi sussidi che riceve la ricerca su carbone, gas e petrolio.<\/p>\n<p><strong><u>Settore trasporto<\/u><\/strong><\/p>\n<p><strong>Il settore \u00e8 sussidiato complessivamente per 16,2 miliardi di euro.\u00a0<\/strong>Di cui<strong>\u00a05.154 milioni<\/strong>\u00a0di euro per il\u00a0<strong>differente trattamento<\/strong>\u00a0fiscale tra benzina e gasolio e\u00a0<strong>3.757 milioni\u00a0<\/strong>di euro per quello tra metano, gpl e benzina; l\u2019esenzione dell\u2019accisa sui carburanti per la\u00a0<strong>navigazione aerea<\/strong>\u00a0ammonta a\u00a0<strong>1.807,3 milioni<\/strong>\u00a0di euro;\u00a0<strong>1.587,5 milioni<\/strong>\u00a0vanno al rimborso delle\u00a0<strong>accise sul gasolio<\/strong>\u00a0per trasporti,\u00a0<strong>400 milioni<\/strong>\u00a0sussidiano\u00a0<strong>l\u2019olio di palme<\/strong>\u00a0nei biocarburanti.<\/p>\n<p><strong><u>Settore agricoltura<\/u><\/strong><\/p>\n<p>Alla\u00a0<strong>PAC<\/strong>\u00a0vanno sussidi per\u00a0<strong>2.117,47 milioni<\/strong>\u00a0di euro. Le\u00a0<strong>esenzioni e riduzioni ai prodotti energetici<\/strong>\u00a0ammontano a\u00a0<strong>939,2 milioni<\/strong>. Tra i sussidi indiretti, la SACE eroga prestiti e garanzie per 155,6 milioni per un impianto di fertilizzanti in Russia.<\/p>\n<p><strong><u>Settore edilizia<\/u><\/strong><\/p>\n<p>Il\u00a0<strong>credito d\u2019imposta per l\u2019acquisto di beni strumentali<\/strong>, generalmente associati a elevati consumi energetici ed emissioni, vale\u00a0<strong>617 milioni<\/strong>\u00a0di euro. L\u2019esenzione dell\u2019<strong>IMU<\/strong>\u00a0per nuovi fabbricati ammonta a\u00a0<strong>38,3<\/strong>\u00a0milioni di euro, sussidiando il consumo di suolo anzich\u00e9 incentivare le ristrutturazioni.<\/p>\n<p><strong><u>Settore canoni e concessioni<\/u><\/strong><\/p>\n<p>L\u2019<strong>inadeguatezza di concessioni e canoni\u00a0<\/strong>equivale a un sussidio di<strong>\u00a0509 milioni,\u00a0<\/strong>tra acque minerali (262), demanio marittimo (150) e cave (97).<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Le richieste di Legambiente al governo<\/u><\/strong><\/p>\n<p>La situazione deve cambiare ora; Legambiente chiede al governo di smettere di fare rinvii su questo tema fondamentale per far uscire l\u2019Italia dalle crisi economica, sociale e ambientale. Il consumo di fonti fossili \u00e8 non solo la causa dei cambiamenti climatici ma anche dell\u2019inquinamento delle citt\u00e0, con drammatiche conseguenze sulla salute, per l\u2019esposizione al PM2,5, ozono, diossido di azoto che vengono stimate in 60 mila morti all\u2019anno in Italia dall\u2019Agenzia europea dell\u2019ambiente.<\/p>\n<p><strong>Sono tre le scelte da prendere nei prossimi mesi<\/strong>: inserire nel Recovery plan le scelte di cancellazione di tutti i sussidi alle fossili entro il 2030, eliminare subito i sussidi diretti alle fossili e per lo sfruttamento dei beni ambientali e aggiornare il Catalogo dei sussidi, rivedere subito la tassazione sui combustibili fossili per portare trasparenza e legare la fiscalit\u00e0 alle emissioni di gas serra.<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><strong> Inserire nel Recovery plan le scelte di cancellazione di tutti i sussidi alle fossili entro il 2030.\u00a0<\/strong>Il primo intervento da realizzare dovrebbe essere di chiarire la tassazione sui diversi tipi di combustibili fossili e di cancellare tutte le esclusioni dalle accise esistenti, secondo il principio \u201cchi inquina paga\u201d legando la fiscalit\u00e0 alle emissioni di gas serra. Il secondo intervento deve essere di trasformare gli esoneri dalle accise per i consumi di benzina e gasolio nei trasporti, per l\u2019accisa e l\u2019Iva dei consumi di gas nel riscaldamento civile e nell\u2019industria in incentivi a interventi di efficienza energetica per produrre una riduzione dei consumi e autoprodursi l\u2019energia da rinnovabili.<\/li>\n<li><strong> Eliminare subito i sussidi diretti alle fossili e per lo sfruttamento dei beni ambientali e aggiornare il Catalogo dei sussidi.\u00a0<\/strong>Il governo deve accelerare i lavori della Commissione del ministero dell\u2019Ambiente istituita lo scorso anno e allargare il campo dei sussidi da tagliare subito, perch\u00e9 non ha senso considerare solo quelli che riguardano i combustibili. Sono ampi quelli di cui beneficia il settore dell\u2019oil&amp;gas, come quelli per i canoni per l\u2019estrazione di materiali, tutti i finanziamenti pubblici attraverso il gruppo SACE, gli essenziali, i fondi per la ricerca su gas, carbone e petrolio. Fuori dal settore energetico, ci sono il trattamento fiscale differente tra benzina e gasolio o le agevolazioni IVA per i prodotti fitosanitari o tutti i canoni agevolati nelle attivit\u00e0 di estrazione.\u00a0 Nel nostro dossier individuiamo 13,8 miliardi su cui si pu\u00f2 intervenire da qui al 2025. Senza dimenticare di\u00a0aggiornare il Catalogo dei sussidi inserendo le 13 voci mancanti per un totale di 11,7 miliardi euro<\/li>\n<li><strong> Rivedere subito la tassazione sui combustibili fossili per portare trasparenza e legare la fiscalit\u00e0 alle emissioni di gas serra.\u00a0<\/strong>In Italia la tassazione di combustibili e carburanti non \u00e8 legata alle emissioni di gas serra. L\u2019obiettivo delle politiche energetiche e dei trasporti deve essere di ridurre le emissioni di CO<sub>2<\/sub>prodotte. Per questo la tassazione deve essere legata alle emissioni di carbonio fossile in ogni passaggio fiscale (dalla tassa di propriet\u00e0 per gli autoveicoli, all\u2019acquisto di combustibili per il trasporto e di fonti per il riscaldamento, ecc.).<\/li>\n<\/ol>\n<p><a href=\"http:\/\/www.comunirinnovabili.it\/stop-sussidi-alle-fonti-fossili-e-ambientalmente-dannosi\/\">http:\/\/www.comunirinnovabili.it\/stop-sussidi-alle-fonti-fossili-e-ambientalmente-dannosi\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong><a href=\"https:\/\/a2f3e0.emailsp.com\/frontend\/forms\/Subscription.aspx?idList=3&amp;idForm=6&amp;guid=3a0cb849-9df7-455a-8512-dc7199ae3fd8\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong><\/h3>\n<h3><strong><a href=\"https:\/\/www.lanuovaecologia.it\/acquista\/\">SOSTIENI IL MENSILE<\/a><\/strong><\/h3>\n<\/p>\n<p align=\"right\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora rinvii nonostante gli impegni del governo: 35,7 miliardi sottratti all\u2019innovazione ambientale. Legambiente presenta il Rapporto Stop sussidi alle fonti fossili e ambientalmente dannosi &nbsp; Anche il 2020 si chiude senza tagli ai sussidi alle fonti fossili; nella legge di bilancio presentata dal governo il tema non \u00e8 previsto, nonostante sia stata istituita quest\u2019anno una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"Ancora rinvii nonostante gli impegni del governo: 35,7 miliardi sottratti all\u2019innovazione ambientale. Legambiente presenta il Rapporto Stop sussidi alle fonti fossili e ambientalmente dannosi &nbsp; Anche il 2020 si chiude senza tagli ai sussidi alle fonti fossili; nella legge di bilancio presentata dal governo il tema non \u00e8 previsto, nonostante sia stata istituita quest\u2019anno una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-07T09:57:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-18T12:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili\",\"datePublished\":\"2020-12-07T09:57:11+00:00\",\"dateModified\":\"2021-01-18T12:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/\"},\"wordCount\":1954,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/fossili-contro-solare_1.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/\",\"name\":\"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/fossili-contro-solare_1.jpg\",\"datePublished\":\"2020-12-07T09:57:11+00:00\",\"dateModified\":\"2021-01-18T12:33:06+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/fossili-contro-solare_1.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/12\\\/fossili-contro-solare_1.jpg\",\"width\":448,\"height\":301},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\\\/\\\/forumqualenergia.it\"],\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/ecfrm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/","og_locale":"it_IT","og_type":"article","og_title":"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili - ForumQualEnergia 2023","og_description":"Ancora rinvii nonostante gli impegni del governo: 35,7 miliardi sottratti all\u2019innovazione ambientale. Legambiente presenta il Rapporto Stop sussidi alle fonti fossili e ambientalmente dannosi &nbsp; Anche il 2020 si chiude senza tagli ai sussidi alle fonti fossili; nella legge di bilancio presentata dal governo il tema non \u00e8 previsto, nonostante sia stata istituita quest\u2019anno una [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2020-12-07T09:57:11+00:00","article_modified_time":"2021-01-18T12:33:06+00:00","og_image":[{"width":448,"height":301,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/"},"author":{"name":"ecfrm","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili","datePublished":"2020-12-07T09:57:11+00:00","dateModified":"2021-01-18T12:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/"},"wordCount":1954,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/","url":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/","name":"Il 2020 si chiude senza il taglio dei sussidi alle fonti fossili - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg","datePublished":"2020-12-07T09:57:11+00:00","dateModified":"2021-01-18T12:33:06+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/il-2020-si-chiude-senza-il-taglio-dei-sussidi-alle-fonti-fossili\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2020\/12\/fossili-contro-solare_1.jpg","width":448,"height":301},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=1838"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/1839"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=1838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=1838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=1838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}