{"id":1916,"date":"2021-02-12T16:53:36","date_gmt":"2021-02-12T15:53:36","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/"},"modified":"2021-02-12T16:53:36","modified_gmt":"2021-02-12T15:53:36","slug":"recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/","title":{"rendered":"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221;"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" loading=\"lazy\" style=\"display: block; margin-bottom: 5px; clear:both;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-150x100-1.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Distinguere tra sistemi di riscaldamento fossili e impianti &#8216;green&#8217; per regolare l\u2019accesso al superbonus del 110%. E se la normativa non cambia, escludere da subito le caldaie a gas dalla proroga degli incentivi prevista dal Piano nazionale di ripresa e resilienza (Pnrr). \u00c8 la richiesta al centro della campagna \u201cPer la decarbonizzazione degli impianti di riscaldamento negli edifici\u201d lanciata da Legambiente e Kyoto Club.<\/p>\n<p>\u201cSul mercato esistono gi\u00e0 diverse alternative \u201cgreen\u201d e competitive dal punto di vista economico, come le pompe di calore \u2013 sostengono <strong>Edoardo Zanchini, vicepresidente di Legambiente, e Sergio Andreis, direttore di Kyoto Club <\/strong>&#8211; Quella del Superbonus \u00e8 una strada certamente corretta, ma migliorabile. Gli oltre 20 miliardi destinati al provvedimento sono sovrastimati e sottraggono risorse fondamentali ad altre iniziative che vanno nella direzione della decarbonizzazione. Una parte degli incentivi potrebbero essere risparmiati limitandone l\u2019erogazione a sistemi di riscaldamento che impiegano fonti energetiche rinnovabili\u201d.<\/p>\n<blockquote>\n<p>Quella del Superbonus \u00e8 una strada certamente corretta, ma migliorabile. Gli oltre 20 miliardi destinati al provvedimento sono sovrastimati e sottraggono risorse fondamentali ad altre iniziative che vanno nella direzione della decarbonizzazione &#8211; <strong>Zanchini (Legambiente) e Andreis (Kyoto Club)<\/strong><\/p>\n<\/blockquote>\n<p>Da un recente studio pubblicato dal Cresme (Centro ricerche economiche, sociologiche e di mercato nell&#8217;edilizia) \u00e8 emerso che il riscaldamento domestico \u00e8 una delle principali cause di inquinamento urbano in Italia, ed \u00e8 responsabile di oltre il 19% delle emissioni prodotte dal nostro Paese e il 60% di polveri sottili nelle aree urbane. In Italia sono installate pi\u00f9 di 19 milioni di caldaie a gas e si stima che pi\u00f9 di 7 milioni di esse siano antecedenti alla Direttiva 90\/396 \/ CE sulle prestazioni degli apparecchi a gas, con il rischio di essere sostituite da altri impianti a gas, che sarebbero pi\u00f9 efficienti, ma di non affrontare il problema dell&#8217;inquinamento locale e globale che producono.<\/p>\n<blockquote>\n<p>Il riscaldamento domestico \u00e8 una delle principali cause di inquinamento urbano in Italia, ed \u00e8 responsabile di oltre il 19% delle emissioni prodotte dal nostro Paese e il 60% di polveri sottili nelle aree urbane &#8211; <strong>Studio Cresme <\/strong><\/p>\n<\/blockquote>\n<p>&#8220;Se vogliamo centrare gli obiettivi europei di riduzione delle emissioni del 55% in dieci anni, \u00e8 necessario agire subito e puntare alla decarbonizzazione del sistema energetico italiano anche attraverso la graduale &#8216;rottamazione&#8217; dei dispositivi di riscaldamento a metano, gpl e gasolio, a partire dai pi\u00f9 inefficienti&#8221;, sostengono le associazioni. &#8220;In alcuni paesi europei &#8211; Svezia, Paesi Bassi e Regno Unito &#8211; \u00e8 gi\u00e0 stata stabilita la data entro la quale sar\u00e0 vietato installare sistemi di riscaldamento da combustibili fossili. Ci auguriamo che la stessa scelta venga fatta anche in Italia&#8221;.<\/p>\n<h2>Le richieste di Legambiente e Kyoto Club<\/h2>\n<ul>\n<li>L\u2019esclusione dal PNRR dell&#8217;estensione del credito d&#8217;imposta del 110% per i sistemi di riscaldamento a combustibili fossili.<\/li>\n<li>La revisione della legislazione sulla progettazione ecocompatibile e sull&#8217;etichettatura energetica sulle caldaie per garantire che nei piani di recupero italiani non siano inclusi regimi di sovvenzione per il riscaldamento a combustibili fossili e che sia incluso il riscaldamento da fonti rinnovabili.<\/li>\n<li>Vietare l\u2019installazione di impianti fossili nei nuovi edifici.<\/li>\n<li>Eliminare gradualmente le caldaie per il riscaldamento a combustibili fossili attraverso il regolamento sulla progettazione ecocompatibile e una revisione dell&#8217;etichetta energetica.<\/li>\n<li>Puntare sulla smartizzazione e sulla digitalizzazione per migliorare la prestazione degli impianti.<\/li>\n<li>Vietare, dal primo gennaio 2025, l\u2019installazione di impianti fossili e prevedere l\u2019obbligo di installare esclusivamente impianti da fonti rinnovabili o che non producono emissioni inquinanti e climalteranti.<\/li>\n<\/ul>\n<h3 data-wahfont=\"22\"><strong><a href=\"https:\/\/a2f3e0.emailsp.com\/frontend\/forms\/Subscription.aspx?idList=3&amp;idForm=6&amp;guid=3a0cb849-9df7-455a-8512-dc7199ae3fd8\" data-wahfont=\"22\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong><\/h3>\n<h3 data-wahfont=\"22\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/acquista\/\" data-wahfont=\"22\">SOSTIENI IL MENSILE<\/a><\/strong><\/h3>\n<\/p>\n<p align=\"right\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Distinguere tra sistemi di riscaldamento fossili e impianti &#8216;green&#8217; per regolare l\u2019accesso al superbonus del 110%. E se la normativa non cambia, escludere da subito le caldaie a gas dalla proroga degli incentivi prevista dal Piano nazionale di ripresa e resilienza (Pnrr). \u00c8 la richiesta al centro della campagna \u201cPer la decarbonizzazione degli impianti di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-1916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221; - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221; - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"Distinguere tra sistemi di riscaldamento fossili e impianti &#8216;green&#8217; per regolare l\u2019accesso al superbonus del 110%. E se la normativa non cambia, escludere da subito le caldaie a gas dalla proroga degli incentivi prevista dal Piano nazionale di ripresa e resilienza (Pnrr). \u00c8 la richiesta al centro della campagna \u201cPer la decarbonizzazione degli impianti di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-12T15:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221;\",\"datePublished\":\"2021-02-12T15:53:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/02\\\/heating-949081_1920-696x522-1-300x200-1.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/\",\"name\":\"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221; - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/02\\\/heating-949081_1920-696x522-1-300x200-1.jpg\",\"datePublished\":\"2021-02-12T15:53:36+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/02\\\/heating-949081_1920-696x522-1-300x200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/02\\\/heating-949081_1920-696x522-1-300x200-1.jpg\",\"width\":300,\"height\":200},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\\\/\\\/forumqualenergia.it\"],\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/ecfrm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221; - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/","og_locale":"it_IT","og_type":"article","og_title":"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221; - ForumQualEnergia 2023","og_description":"Distinguere tra sistemi di riscaldamento fossili e impianti &#8216;green&#8217; per regolare l\u2019accesso al superbonus del 110%. E se la normativa non cambia, escludere da subito le caldaie a gas dalla proroga degli incentivi prevista dal Piano nazionale di ripresa e resilienza (Pnrr). \u00c8 la richiesta al centro della campagna \u201cPer la decarbonizzazione degli impianti di [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2021-02-12T15:53:36+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/"},"author":{"name":"ecfrm","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221;","datePublished":"2021-02-12T15:53:36+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/"},"wordCount":560,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/","url":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/","name":"Recovery plan, &#8220;stop ai finanziamenti alle caldaie fossili&#8221; - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg","datePublished":"2021-02-12T15:53:36+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/recovery-plan-stop-ai-finanziamenti-alle-caldaie-fossili\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/02\/heating-949081_1920-696x522-1-300x200-1.jpg","width":300,"height":200},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/1917"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}