{"id":2002,"date":"2021-04-19T11:27:43","date_gmt":"2021-04-19T09:27:43","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/"},"modified":"2021-09-03T09:33:03","modified_gmt":"2021-09-03T07:33:03","slug":"lefficacia-nelle-erbe-il-rigore-del-laboratorio","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/","title":{"rendered":"L\u2019efficacia nelle erbe il rigore del laboratorio"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"2480\" height=\"1176\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" loading=\"lazy\" style=\"display: block; margin: auto; margin-bottom: 5px;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 2480w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 1024w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 768w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 1536w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 2048w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 696w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 1068w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg 1920w\" sizes=\"auto, (max-width: 2480px) 100vw, 2480px\" \/><\/p>\n<h6><strong>Erbe, fiori, piante godono oggi di un eccezionale favore di pubblico, <\/strong>ma nel 1976, quando <strong>Helan <\/strong>\u00e8 nata con il preciso scopo di produrre cosmetici naturali, sembrava che le genuine tradizioni e la secolare sapienza erboristica fossero assopite, sopraffatte da una sfrenata rincorsa al modernismo.<\/h6>\n<p>\u00c8 stata un\u2019illimitata fiducia nella bont\u00e0 di una visione del mondo in chiave naturale quella che ha spinto Helan a produrre linee cosmetiche realizzate con oli ed estratti vegetali, essenze, mieli e acque aromatiche che potessero donare benessere e bellezza in virt\u00f9 della loro ricchezza di principi attivi e della loro altissima affinit\u00e0 cutanea.<br \/>\nIn virt\u00f9 dell\u2019esperienza acquisita in tanti anni di ricerca formulativa con l\u2019impiego di sostanze naturali, Helan ha realizzato una nuova tipologia di prodotti funzionali:<strong> Pomate, Gel e Unguenti.<\/strong><\/p>\n<p><a href=\"https:\/\/helan.com\/linee\/i-rimedi-di-helan---pomate\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-243879 size-medium\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg\" alt=\"\" width=\"300\" height=\"182\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 1024w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 768w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 1536w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 2048w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 696w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 1068w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_prodotti.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Formulati con un altissimo contenuto di estratti secchi, <strong>titolati 1:4<\/strong>, cio\u00e8 quattro volte pi\u00f9 concentrati, unitamente a un\u2019ampia selezione di oli essenziali idonei allo scopo del prodotto, che hanno permesso di formulare senza profumo e hanno consentito di realizzare prodotti espressamente mirati ad alleviare il disturbo che si \u00e8 voluto contrastare con risultati sorprendentemente efficaci.<\/p>\n<p>Agli estratti secchi e fluidi, sono state abbinate le acque biologiche, gli iperfermentati ottenuti con una nuova tecnologia, i melliti e gli oleoliti preparati direttamente dal nostro laboratorio R&amp;Q per la migliore attivit\u00e0 dei prodotti.<\/p>\n<p><a href=\"https:\/\/helan.com\/linee\/i-rimedi-di-helan---pomate\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-243878 size-medium\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg\" alt=\"\" width=\"284\" height=\"300\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 284w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 969w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 768w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 1453w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 1938w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 696w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 1068w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/112P1_group-copia-1.jpg 1920w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/a><\/p>\n<p>All\u2019interno della <a href=\"https:\/\/helan.com\/linee\/i-rimedi-di-helan---pomate\/\"><strong>Linea<\/strong> <strong>I Rimedi di Helan<\/strong> troviamo 11 referenze tra pomate, gel e unguenti (vai al catalogo online)<\/a>, tra cui <strong>l\u2019Arnica Pomata concentrata<\/strong>.<\/p>\n<p>Formulata sia con l\u2019estratto secco titolato che con l\u2019oleolito di fiori d\u2019Arnica montana, in sinergia con Consolida, oli essenziali di Cipresso, Pino marittimo e Timo bianco, Acqua di Menta bio contribuisce ad alleviare e proteggere efficacemente la cute coinvolta dal disagio. Contrasta affaticamenti e tensioni muscolari e risulta essere ideale per il massaggio, anche quello sportivo.<\/p>\n<p>&nbsp;<\/p>\n<h3 data-wahfont=\"22\"><\/h3>\n<h3 data-wahfont=\"22\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/iscrizione-newsletter\/\" data-wahfont=\"22\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong><\/h3>\n<h3 data-wahfont=\"22\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/acquista\/\" data-wahfont=\"22\">SOSTIENI IL MENSILE<\/a><\/strong><\/h3>\n<\/p>\n<p align=\"right\"><strong>Aziende Amiche<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erbe, fiori, piante godono oggi di un eccezionale favore di pubblico, ma nel 1976, quando Helan \u00e8 nata con il preciso scopo di produrre cosmetici naturali, sembrava che le genuine tradizioni e la secolare sapienza erboristica fossero assopite, sopraffatte da una sfrenata rincorsa al modernismo. \u00c8 stata un\u2019illimitata fiducia nella bont\u00e0 di una visione del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019efficacia nelle erbe il rigore del laboratorio - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019efficacia nelle erbe il rigore del laboratorio - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"Erbe, fiori, piante godono oggi di un eccezionale favore di pubblico, ma nel 1976, quando Helan \u00e8 nata con il preciso scopo di produrre cosmetici naturali, sembrava che le genuine tradizioni e la secolare sapienza erboristica fossero assopite, sopraffatte da una sfrenata rincorsa al modernismo. \u00c8 stata un\u2019illimitata fiducia nella bont\u00e0 di una visione del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T09:27:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T07:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"L\u2019efficacia nelle erbe il rigore del laboratorio\",\"datePublished\":\"2021-04-19T09:27:43+00:00\",\"dateModified\":\"2021-09-03T07:33:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/\"},\"wordCount\":319,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/04\\\/linea_I_Rimedi_di_Helan_banner.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/\",\"name\":\"L\u2019efficacia nelle erbe il rigore del laboratorio - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/04\\\/linea_I_Rimedi_di_Helan_banner.jpg\",\"datePublished\":\"2021-04-19T09:27:43+00:00\",\"dateModified\":\"2021-09-03T07:33:03+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/04\\\/linea_I_Rimedi_di_Helan_banner.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/04\\\/linea_I_Rimedi_di_Helan_banner.jpg\",\"width\":2480,\"height\":1176},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\\\/\\\/forumqualenergia.it\"],\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/ecfrm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019efficacia nelle erbe il rigore del laboratorio - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019efficacia nelle erbe il rigore del laboratorio - ForumQualEnergia 2023","og_description":"Erbe, fiori, piante godono oggi di un eccezionale favore di pubblico, ma nel 1976, quando Helan \u00e8 nata con il preciso scopo di produrre cosmetici naturali, sembrava che le genuine tradizioni e la secolare sapienza erboristica fossero assopite, sopraffatte da una sfrenata rincorsa al modernismo. \u00c8 stata un\u2019illimitata fiducia nella bont\u00e0 di una visione del [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2021-04-19T09:27:43+00:00","article_modified_time":"2021-09-03T07:33:03+00:00","og_image":[{"width":2480,"height":1176,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/"},"author":{"name":"ecfrm","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"L\u2019efficacia nelle erbe il rigore del laboratorio","datePublished":"2021-04-19T09:27:43+00:00","dateModified":"2021-09-03T07:33:03+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/"},"wordCount":319,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/","url":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/","name":"L\u2019efficacia nelle erbe il rigore del laboratorio - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg","datePublished":"2021-04-19T09:27:43+00:00","dateModified":"2021-09-03T07:33:03+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/lefficacia-nelle-erbe-il-rigore-del-laboratorio\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/04\/linea_I_Rimedi_di_Helan_banner.jpg","width":2480,"height":1176},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/2002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=2002"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/2002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/2005"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=2002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=2002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=2002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}