{"id":2041,"date":"2021-05-13T19:50:25","date_gmt":"2021-05-13T17:50:25","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/il-13-maggio-lovershoot-day-per-litalia\/"},"modified":"2021-05-14T08:33:04","modified_gmt":"2021-05-14T06:33:04","slug":"il-13-maggio-lovershoot-day-per-litalia","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/il-13-maggio-lovershoot-day-per-litalia\/","title":{"rendered":"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1-300x225.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" loading=\"lazy\" style=\"display: block; margin-bottom: 5px; clear:both;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1-300x225.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h6><strong>Lo segnala il Global footprint network, che calcola l&#8217;impronta ecologica di ciascun Paese e quello globale. Dal 14 e fino alla fine dell&#8217;anno in corso il nostro Paese andr\u00e0 in debito con la Terra<\/strong><\/h6>\n<p>Per il 2021 l&#8217;Italia ha gi\u00e0 esaurito oggi, 13 maggio, le risorse naturali a disposizione. Il nostro Paese ha dunque gi\u00e0 raggiunto l&#8217;overshoot day. Ci\u00f2 significa che da domani e fino alla fine dell&#8217;anno in corso l&#8217;Italia andr\u00e0 in debito con la Terra.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-244952 size-full\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/763686c178f2404168a003f0367f76c3-min.jpeg\" alt=\"overshoot day Italia\" width=\"700\" height=\"566\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/763686c178f2404168a003f0367f76c3-min.jpeg 700w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/763686c178f2404168a003f0367f76c3-min-300x243.jpeg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/763686c178f2404168a003f0367f76c3-min.jpeg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/763686c178f2404168a003f0367f76c3-min.jpeg 696w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Lo segnala il Global footprint network, che calcola l&#8217;impronta ecologica di ciascun Paese e quello globale, che nel 2020 \u00e8 caduto il 22 agosto. Stando alle stime della piattaforma, l&#8217;Italia avrebbe bisogno delle risorse di 2,7 Terre per arrivare alla fine dell&#8217;anno alimentata esclusivamente dalle proprie risorse. L&#8217;anno scorso l&#8217;Italia ha avuto l&#8217;overshoot day il 14 maggio e due anni fa il 15 maggio.<\/p>\n<h3 data-wahfont=\"22\"><strong><a href=\"https:\/\/a2f3e0.emailsp.com\/frontend\/forms\/Subscription.aspx?idList=3&amp;idForm=6&amp;guid=3a0cb849-9df7-455a-8512-dc7199ae3fd8\" data-wahfont=\"22\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong><\/h3>\n<h3 data-wahfont=\"22\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/acquista\/\" data-wahfont=\"22\">SOSTIENI IL MENSILE<\/a><\/strong><\/h3>\n<\/p>\n<p align=\"right\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo segnala il Global footprint network, che calcola l&#8217;impronta ecologica di ciascun Paese e quello globale. Dal 14 e fino alla fine dell&#8217;anno in corso il nostro Paese andr\u00e0 in debito con la Terra Per il 2021 l&#8217;Italia ha gi\u00e0 esaurito oggi, 13 maggio, le risorse naturali a disposizione. Il nostro Paese ha dunque gi\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 13 maggio l&#8217;overshoot day per l&#8217;Italia - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"Lo segnala il Global footprint network, che calcola l&#8217;impronta ecologica di ciascun Paese e quello globale. Dal 14 e fino alla fine dell&#8217;anno in corso il nostro Paese andr\u00e0 in debito con la Terra Per il 2021 l&#8217;Italia ha gi\u00e0 esaurito oggi, 13 maggio, le risorse naturali a disposizione. Il nostro Paese ha dunque gi\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-13T17:50:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-14T06:33:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/il-13-maggio-lovershoot-day-per-litalia\\\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia\",\"datePublished\":\"2021-05-13T17:50:25+00:00\",\"dateModified\":\"2021-05-14T06:33:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/il-13-maggio-lovershoot-day-per-litalia\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/05\\\/satellite-1.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/il-13-maggio-lovershoot-day-per-litalia\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/\",\"name\":\"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/05\\\/satellite-1.jpg\",\"datePublished\":\"2021-05-13T17:50:25+00:00\",\"dateModified\":\"2021-05-14T06:33:04+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/overshoot-day-italia-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/05\\\/satellite-1.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2021\\\/05\\\/satellite-1.jpg\",\"width\":630,\"height\":472},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\\\/\\\/forumqualenergia.it\"],\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/ecfrm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia - ForumQualEnergia 2023","og_description":"Lo segnala il Global footprint network, che calcola l&#8217;impronta ecologica di ciascun Paese e quello globale. Dal 14 e fino alla fine dell&#8217;anno in corso il nostro Paese andr\u00e0 in debito con la Terra Per il 2021 l&#8217;Italia ha gi\u00e0 esaurito oggi, 13 maggio, le risorse naturali a disposizione. Il nostro Paese ha dunque gi\u00e0 [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2021-05-13T17:50:25+00:00","article_modified_time":"2021-05-14T06:33:04+00:00","og_image":[{"width":630,"height":472,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/il-13-maggio-lovershoot-day-per-litalia\/"},"author":{"name":"ecfrm","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia","datePublished":"2021-05-13T17:50:25+00:00","dateModified":"2021-05-14T06:33:04+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/il-13-maggio-lovershoot-day-per-litalia\/"},"wordCount":159,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/il-13-maggio-lovershoot-day-per-litalia\/","url":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/","name":"Il 13 maggio l&#8217;overshoot day per l&#8217;Italia - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg","datePublished":"2021-05-13T17:50:25+00:00","dateModified":"2021-05-14T06:33:04+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/overshoot-day-italia-2021\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2021\/05\/satellite-1.jpg","width":630,"height":472},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/2041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=2041"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/2041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/2042"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=2041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=2041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=2041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}