{"id":3522,"date":"2022-02-04T14:52:48","date_gmt":"2022-02-04T13:52:48","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\/"},"modified":"2022-03-10T18:56:33","modified_gmt":"2022-03-10T17:56:33","slug":"gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\/","title":{"rendered":"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221;"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"420\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" loading=\"lazy\" style=\"display: block; margin: auto; margin-bottom: 5px;max-width: 100%;\" link_thumbnail=\"\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg 630w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg 150w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p><strong><\/p>\n<blockquote>\n<p>Comunit\u00e0 energetiche<br \/>\n<a href=\"https:\/\/www.lanuovaecologia.it\/comunita-energetiche\/\">Scopri lo speciale<\/a><\/p>\n<\/blockquote>\n<p><\/strong><\/p>\n<h6>Dal mensile &#8211; Intervista al direttore scientifico del Kyoto Club che a Nuova Ecologia spiega: &#8220;In Europa il settore del gas \u00e8 molto forte e sa bene di essere a rischio in uno scenario carbon neutral al 2050&#8221;<\/h6>\n<p><span id=\"more-252164\"><\/span><\/p>\n<p><span style=\"font-family: Verdana, BlinkMacSystemFont, -apple-system, 'Segoe UI', Roboto, Oxygen, Ubuntu, Cantarell, 'Open Sans', 'Helvetica Neue', sans-serif;\">Inserire nucleare e gas nella lista delle attivit\u00e0 green, come propone la Commissione europea &#8211; sostiene <\/span><strong style=\"font-family: Verdana, BlinkMacSystemFont, -apple-system, 'Segoe UI', Roboto, Oxygen, Ubuntu, Cantarell, 'Open Sans', 'Helvetica Neue', sans-serif;\">Gianni Silvestrini<\/strong><span style=\"font-family: Verdana, BlinkMacSystemFont, -apple-system, 'Segoe UI', Roboto, Oxygen, Ubuntu, Cantarell, 'Open Sans', 'Helvetica Neue', sans-serif;\"> che di energie rinnovabili si occupa da oltre trent\u2019anni &#8211; potrebbe distogliere risorse dalle fonti pulite. Piuttosto, spiega, bisogna investire sui nuovi sistemi di stoccaggio delle rinnovabili.<\/span><\/p>\n<p><strong>Cosa comporterebbe inserire nucleare e gas nella tassonomia Ue?<\/strong><\/p>\n<figure id=\"attachment_252167\" aria-describedby=\"caption-attachment-252167\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-252167 size-medium\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/Gianni-Silvestrini-Forum-copia.jpg\" alt=\"\" width=\"300\" height=\"236\" srcset=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/Gianni-Silvestrini-Forum-copia.jpg 300w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/Gianni-Silvestrini-Forum-copia.jpg 150w, https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/Gianni-Silvestrini-Forum-copia.jpg 591w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-252167\" class=\"wp-caption-text\">Gianni Silvestrini, direttore scientifico Kyoto Club<\/figcaption><\/figure>\n<p>Intanto far diventare tutto \u201cverde\u201d rischia di togliere credibilit\u00e0 alla tassonomia. E in seconda battuta, concretamente, la finanza privata aspetta queste scelte proprio per orientare i propri investimenti e cos\u00ec rischiamo che parte di questi vadano su gas e nucleare invece che sulle rinnovabili. Per quanto riguarda l\u2019Italia, sul gas i parametri indicati probabilmente escludono i nostri impianti e quindi non sarebbero in ogni caso finanziabili, mentre credo che il nucleare da noi alla fine non si far\u00e0: \u00e8 solo propaganda.<\/p>\n<p><strong>La Commissione ha accolto le richieste di alcuni Paesi e quelle dei settori nucleare e fossile: le rinnovabili non hanno ancora abbastanza forza per imporsi?<\/strong><\/p>\n<p>In Europa il settore del gas \u00e8 molto forte e sa bene di essere a rischio in uno scenario carbon neutral al 2050, per questo sta puntando sull\u2019idrogeno e ha bisogno di una corsia preferenziale. Insomma, la pressione del mondo del gas sulla Commissione \u00e8 stata molto forte e la stessa cosa vale per il nucleare. Le rinnovabili, dal canto loro, stanno crescendo rapidamente, \u00e8 vero, ma non abbastanza. E poi il loro mondo produttivo \u00e8 in Asia, non in Europa, e questo fa una gran differenza per poter contare. Le cose, per\u00f2, potrebbero cambiare presto perch\u00e9 l\u2019Europa si \u00e8 accorta dell\u2019errore e adesso sta puntando molto sul reshoring: vuole far tornare in Europa le fabbriche che producono i vari componenti. Se lo far\u00e0 quando si inizier\u00e0 a correre davvero sulle rinnovabili \u2013 e io penso che la corsa ci sar\u00e0 perch\u00e9 solo in Italia dovremo passare dal 36-38% attuale al 70% di rinnovabili nel 2030 \u2013 il comparto si rafforzer\u00e0 e il rapporto di forza con le altre fonti di energia potr\u00e0 cambiare.<\/p>\n<p><strong>Una delle critiche di chi sostiene nucleare e gas \u00e8 la poca stabilit\u00e0 delle fonti di energia rinnovabili.<\/strong><\/p>\n<p>S\u00ec, \u00e8 una delle argomentazioni usate, e avrebbero anche ragione se non ci fosse una risposta. Ma la risposta c\u2019\u00e8: chi marcia con pi\u00f9 decisione verso il 100% delle rinnovabili, come la Germania o la California, si sta gi\u00e0 attrezzando per l\u2019accumulo di energia stagionale, per quando mancano sole e vento. A Los Angeles, per esempio, vogliono produrre idrogeno dal solare e dall\u2019eolico per poi stoccarlo in caverne di sale ed estrarlo e usarlo per produrre energia elettrica quando serve. Questa \u00e8 la strada, in Italia purtroppo non stiamo investendo risorse su questo fronte mentre in Germania e negli Usa lo stanno gi\u00e0 facendo perch\u00e9 hanno capito che sar\u00e0 fondamentale farlo.<\/p>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/iscrizione-newsletter\/\" data-wahfont=\"27\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong>\u00a0<\/span><\/h2>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/promo\/\" data-wahfont=\"27\">REGISTRATI SUL SITO<\/a><\/strong><\/span><\/h2>\n<\/p>\n<p align=\"right\"><strong>Tiziana Guerrisi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunit\u00e0 energetiche Scopri lo speciale Dal mensile &#8211; Intervista al direttore scientifico del Kyoto Club che a Nuova Ecologia spiega: &#8220;In Europa il settore del gas \u00e8 molto forte e sa bene di essere a rischio in uno scenario carbon neutral al 2050&#8221; Inserire nucleare e gas nella lista delle attivit\u00e0 green, come propone la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221; - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221; - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"Comunit\u00e0 energetiche Scopri lo speciale Dal mensile &#8211; Intervista al direttore scientifico del Kyoto Club che a Nuova Ecologia spiega: &#8220;In Europa il settore del gas \u00e8 molto forte e sa bene di essere a rischio in uno scenario carbon neutral al 2050&#8221; Inserire nucleare e gas nella lista delle attivit\u00e0 green, come propone la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-04T13:52:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-10T17:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nasfo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nasfo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\\\/\"},\"author\":{\"name\":\"nasfo\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/9e50ded2274ae411b7ca39e7ec9eee62\"},\"headline\":\"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221;\",\"datePublished\":\"2022-02-04T13:52:48+00:00\",\"dateModified\":\"2022-03-10T17:56:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\\\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/shutterstock_305419862-copia.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/\",\"name\":\"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221; - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/shutterstock_305419862-copia.jpg\",\"datePublished\":\"2022-02-04T13:52:48+00:00\",\"dateModified\":\"2022-03-10T17:56:33+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/shutterstock_305419862-copia.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/shutterstock_305419862-copia.jpg\",\"width\":630,\"height\":420},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/9e50ded2274ae411b7ca39e7ec9eee62\",\"name\":\"nasfo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ace28799218935dc789fbe0b71585ba407a576e81da9858e66c62ec4118e684c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ace28799218935dc789fbe0b71585ba407a576e81da9858e66c62ec4118e684c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ace28799218935dc789fbe0b71585ba407a576e81da9858e66c62ec4118e684c?s=96&d=mm&r=g\",\"caption\":\"nasfo\"},\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/nasfo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221; - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/","og_locale":"it_IT","og_type":"article","og_title":"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221; - ForumQualEnergia 2023","og_description":"Comunit\u00e0 energetiche Scopri lo speciale Dal mensile &#8211; Intervista al direttore scientifico del Kyoto Club che a Nuova Ecologia spiega: &#8220;In Europa il settore del gas \u00e8 molto forte e sa bene di essere a rischio in uno scenario carbon neutral al 2050&#8221; Inserire nucleare e gas nella lista delle attivit\u00e0 green, come propone la [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2022-02-04T13:52:48+00:00","article_modified_time":"2022-03-10T17:56:33+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg","type":"image\/jpeg"}],"author":"nasfo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"nasfo","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\/"},"author":{"name":"nasfo","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/9e50ded2274ae411b7ca39e7ec9eee62"},"headline":"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221;","datePublished":"2022-02-04T13:52:48+00:00","dateModified":"2022-03-10T17:56:33+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\/"},"wordCount":517,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/gas-e-nucleare-green-silvestrini-cosi-togliamo-credibilita-alla-tassonomia\/","url":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/","name":"Gas e nucleare &#8216;green&#8217;, Silvestrini: &#8220;Cos\u00ec togliamo credibilit\u00e0 alla tassonomia&#8221; - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg","datePublished":"2022-02-04T13:52:48+00:00","dateModified":"2022-03-10T17:56:33+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/tassonomia-gas-nucleare-gianni-silvestrini-kyoto-club-intervista\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/02\/shutterstock_305419862-copia.jpg","width":630,"height":420},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/9e50ded2274ae411b7ca39e7ec9eee62","name":"nasfo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ace28799218935dc789fbe0b71585ba407a576e81da9858e66c62ec4118e684c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ace28799218935dc789fbe0b71585ba407a576e81da9858e66c62ec4118e684c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ace28799218935dc789fbe0b71585ba407a576e81da9858e66c62ec4118e684c?s=96&d=mm&r=g","caption":"nasfo"},"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/nasfo\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=3522"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/3523"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=3522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=3522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=3522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}