{"id":3670,"date":"2022-05-05T09:30:46","date_gmt":"2022-05-05T07:30:46","guid":{"rendered":"https:\/\/forumqualenergia.it\/2023\/blog\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\/"},"modified":"2024-09-02T15:33:34","modified_gmt":"2024-09-02T13:33:34","slug":"energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021","status":"publish","type":"post","link":"https:\/\/forumqualenergia.it\/2023\/blog\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\/","title":{"rendered":"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021"},"content":{"rendered":"<p style=\"text-align: left\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"420\" src=\"https:\/\/staging.forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg\" class=\"webfeedsFeaturedVisual wp-post-image\" alt=\"\" style=\"display: block;margin: auto;margin-bottom: 5px;max-width: 100%\" loading=\"lazy\" \/><\/p>\n<h6><strong>La guerra in Ucraina ha ulteriormente aggravato la crisi del gas iniziata lo scorso anno. Un andamento influenzato anche dai cambiamenti climatici. I dati del nuovo rapporto di Falck Renewables Next Solutions\u00a0<\/strong><\/h6>\n<p><span id=\"more-254843\"><\/span><\/p>\n<p><strong>Falck Renewables Next Solutions<\/strong> ha pubblicato il report sull\u2019andamento dei prezzi dell\u2019energia, aumentati del 320% rispetto al primo trimestre 2021 (249.25 \u20ac\/MWh vs 59,31 \u20ac\/MWh), confermando la tendenza di forte crescita gi\u00e0 evidenziata nell&#8217;ultimo trimestre 2021 quando il prezzo medio dell\u2019energia (PUN Prezzo Unico Nazionale rilevato sulla borsa elettrica italiana) ha toccato una media mensile a dicembre di 281,24 \u20ac\/MWh registrando una crescita del 420% rispetto a dicembre 2020 (54.04 \u20ac\/MWh).<\/p>\n<p>I dati relativi al primo trimestre 2022 evidenziano la stessa tendenza al rialzo: il PUN nei tre mesi analizzati viene registrato rispettivamente a 224.5 \u20ac\/MWh, 211,7 \u20ac\/MWh e 308,2 \u20ac\/MWh presentando valori assolutamente fuori scala se rapportati allo stesso periodo del 2021, ma in linea con l\u2019ultimo trimestre, segno che la guerra in Ucraina ha ulteriormente aggravato la crisi del gas iniziata lo scorso anno, contribuendo a rafforzare lo scenario inedito che vede il settore energetico caratterizzato da prezzi che hanno addirittura toccato un picco di 587,67\u20ac\/MWh nella giornata dell&#8217;8 marzo.<\/p>\n<p><strong>La situazione dell\u2019andamento dei prezzi dell\u2019energia \u00e8 influenzata anche dai cambiamenti climatici:<\/strong> il freddo tardivo, abbinato a un\u2019eccezionale carenza di piogge hanno causato un taglio del 50% della produzione di energia da idroelettrico nel nostro Paese. Questa situazione \u00e8 stata parzialmente compensata da una buona produzione di energia eolica nel Sud Italia favorita da un inverno molto ventoso. Le regioni meridionali, infatti, hanno beneficiato pi\u00f9 di tutte dell&#8217;elevata ventosit\u00e0, riportando nel mese di marzo sconti sul prezzo giornaliero dell\u2019energia anche di 180 \u20ac\/MWh e 140 \u20ac\/MWh dovuti alla maggiore immissione in rete di energia rinnovabile.<\/p>\n<p>Il settore delle energie rinnovabili, che oggi accusa procedure troppo complesse per uno sviluppo rapido in grado di incidere sulla crisi in atto, \u00e8 in attesa degli affetti del Decreto Energia appena approvato, nel quale sono previste semplificazioni per gli iter autorizzativi necessari all\u2019installazione di nuovi impianti e allo sblocco di oltre 60 GW in attesa di autorizzazione. Questa nuova potenza rinnovabile potrebbe far risparmiare all\u2019Italia 15 miliardi di m<sup>3\u00a0<\/sup>di gas ogni anno, ovvero il 20% del gas importato, dando cos\u00ec una svolta ai costi in bolletta, secondo i dati di\u00a0Elettricit\u00e0 Futura riferiti a febbraio 2022.<\/p>\n<p>\u201cI dati sono fondamentali per analizzare e programmare il futuro del nostro settore, e lo sono ancora di pi\u00f9 in situazioni come quella attuale\u201d spiega <strong>Luca Prosdocimi, Head of Trading di Falck Renewables Next Solutions<\/strong>. \u201cEcco perch\u00e9 da oltre due anni la nostra divisione fornisce a clienti e operatori un servizio di overview del mercato elettrico. Quest\u2019ultimo report evidenzia in modo significativo l\u2019escalation a cui i prezzi sono soggetti, con una visione che nello scenario attuale, purtroppo, non tender\u00e0 a migliorare\u201d.<\/p>\n<p>\u201cIl report rilasciato conferma senza dubbio che per svincolarci dalla dipendenza strategica ed economica del gas dobbiamo puntare sempre di pi\u00f9 sulle rinnovabili. \u00c8 quindi chiaro come il settore sia strategico per lo sviluppo energetico del Paese e, di conseguenza, abbiamo bisogno che le Istituzioni supportino la sua crescita\u201d, conclude <strong>Francesco Benvenuto, Head of Energy Management di Falck Renewables Next Solutions<\/strong>.<\/p>\n<div class=\"td_block_wrap tdb_single_content tdi_94 td-pb-border-top td_block_template_12 td-post-content tagdiv-type\" data-td-block-uid=\"tdi_94\">\n<div class=\"tdb-block-inner td-fix-index\">\n<div class=\"td_block_wrap tdb_single_content tdi_105 td-pb-border-top td_block_template_12 td-post-content tagdiv-type\" data-td-block-uid=\"tdi_105\">\n<div class=\"tdb-block-inner td-fix-index\">\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/iscrizione-newsletter\/\" data-wahfont=\"27\">ISCRIVITI ALLA NEWSLETTER<\/a><\/strong>\u00a0<\/span><\/h2>\n<h2 data-wahfont=\"27\"><span data-wahfont=\"27\"><strong><a href=\"https:\/\/www.lanuovaecologia.it\/promo\/\" data-wahfont=\"27\">REGISTRATI SUL SITO<\/a><\/strong><\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p align=\"right\"><strong>Redazione<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerra in Ucraina ha ulteriormente aggravato la crisi del gas iniziata lo scorso anno. Un andamento influenzato anche dai cambiamenti climatici. I dati del nuovo rapporto di Falck Renewables Next Solutions\u00a0 Falck Renewables Next Solutions ha pubblicato il report sull\u2019andamento dei prezzi dell\u2019energia, aumentati del 320% rispetto al primo trimestre 2021 (249.25 \u20ac\/MWh vs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021 - ForumQualEnergia 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021 - ForumQualEnergia 2023\" \/>\n<meta property=\"og:description\" content=\"La guerra in Ucraina ha ulteriormente aggravato la crisi del gas iniziata lo scorso anno. Un andamento influenzato anche dai cambiamenti climatici. I dati del nuovo rapporto di Falck Renewables Next Solutions\u00a0 Falck Renewables Next Solutions ha pubblicato il report sull\u2019andamento dei prezzi dell\u2019energia, aumentati del 320% rispetto al primo trimestre 2021 (249.25 \u20ac\/MWh vs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/\" \/>\n<meta property=\"og:site_name\" content=\"ForumQualEnergia 2023\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T07:30:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T13:33:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecfrm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecfrm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\\\/\"},\"author\":{\"name\":\"ecfrm\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\"},\"headline\":\"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021\",\"datePublished\":\"2022-05-05T07:30:46+00:00\",\"dateModified\":\"2024-09-02T13:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\\\/\"},\"wordCount\":533,\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/05\\\/petrolio-metano.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\\\/\",\"url\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/\",\"name\":\"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021 - ForumQualEnergia 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/05\\\/petrolio-metano.jpg\",\"datePublished\":\"2022-05-05T07:30:46+00:00\",\"dateModified\":\"2024-09-02T13:33:34+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.lanuovaecologia.it\\\/energia-prezzi-aumenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/05\\\/petrolio-metano.jpg\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/05\\\/petrolio-metano.jpg\",\"width\":630,\"height\":420},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"name\":\"ForumQualEnergia 2023\",\"description\":\"Il forum della sostenibilit\u00e0 energetica\",\"publisher\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#organization\",\"name\":\"ForumQualEnergia 2023\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"contentUrl\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/08\\\/forumqualenergia-logo-2023.png\",\"width\":600,\"height\":182,\"caption\":\"ForumQualEnergia 2023\"},\"image\":{\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/#\\\/schema\\\/person\\\/095cb93595434663a0f8291a18071ef3\",\"name\":\"ecfrm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g\",\"caption\":\"ecfrm\"},\"sameAs\":[\"http:\\\/\\\/forumqualenergia.it\"],\"url\":\"https:\\\/\\\/forumqualenergia.it\\\/2023\\\/blog\\\/author\\\/ecfrm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021 - ForumQualEnergia 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/","og_locale":"it_IT","og_type":"article","og_title":"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021 - ForumQualEnergia 2023","og_description":"La guerra in Ucraina ha ulteriormente aggravato la crisi del gas iniziata lo scorso anno. Un andamento influenzato anche dai cambiamenti climatici. I dati del nuovo rapporto di Falck Renewables Next Solutions\u00a0 Falck Renewables Next Solutions ha pubblicato il report sull\u2019andamento dei prezzi dell\u2019energia, aumentati del 320% rispetto al primo trimestre 2021 (249.25 \u20ac\/MWh vs [&hellip;]","og_url":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/","og_site_name":"ForumQualEnergia 2023","article_published_time":"2022-05-05T07:30:46+00:00","article_modified_time":"2024-09-02T13:33:34+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg","type":"image\/jpeg"}],"author":"ecfrm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ecfrm","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/#article","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\/"},"author":{"name":"ecfrm","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3"},"headline":"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021","datePublished":"2022-05-05T07:30:46+00:00","dateModified":"2024-09-02T13:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/forumqualenergia.it\/2023\/blog\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\/"},"wordCount":533,"publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/forumqualenergia.it\/2023\/blog\/energia-prezzi-aumentati-del-320-rispetto-al-primo-trimestre-2021\/","url":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/","name":"Energia, prezzi aumentati del 320% rispetto al primo trimestre 2021 - ForumQualEnergia 2023","isPartOf":{"@id":"https:\/\/forumqualenergia.it\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/#primaryimage"},"image":{"@id":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/#primaryimage"},"thumbnailUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg","datePublished":"2022-05-05T07:30:46+00:00","dateModified":"2024-09-02T13:33:34+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lanuovaecologia.it\/energia-prezzi-aumenti\/#primaryimage","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2022\/05\/petrolio-metano.jpg","width":630,"height":420},{"@type":"WebSite","@id":"https:\/\/forumqualenergia.it\/2023\/#website","url":"https:\/\/forumqualenergia.it\/2023\/","name":"ForumQualEnergia 2023","description":"Il forum della sostenibilit\u00e0 energetica","publisher":{"@id":"https:\/\/forumqualenergia.it\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forumqualenergia.it\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forumqualenergia.it\/2023\/#organization","name":"ForumQualEnergia 2023","url":"https:\/\/forumqualenergia.it\/2023\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","contentUrl":"https:\/\/forumqualenergia.it\/2023\/wp-content\/uploads\/sites\/24\/2025\/08\/forumqualenergia-logo-2023.png","width":600,"height":182,"caption":"ForumQualEnergia 2023"},"image":{"@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/forumqualenergia.it\/2023\/#\/schema\/person\/095cb93595434663a0f8291a18071ef3","name":"ecfrm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d57bc624aee8f4a8b39f170335c749e82fc3f234e6e631db00e4b9caca38bfa?s=96&d=mm&r=g","caption":"ecfrm"},"sameAs":["http:\/\/forumqualenergia.it"],"url":"https:\/\/forumqualenergia.it\/2023\/blog\/author\/ecfrm\/"}]}},"_links":{"self":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/comments?post=3670"}],"version-history":[{"count":0,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/posts\/3670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media\/3671"}],"wp:attachment":[{"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/media?parent=3670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/categories?post=3670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forumqualenergia.it\/2023\/wp-json\/wp\/v2\/tags?post=3670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}